{"id":29821,"date":"2025-07-17T21:22:34","date_gmt":"2025-07-17T19:22:34","guid":{"rendered":"https:\/\/nuscospa.com\/vendita-infissi-in-pvc-pavia\/"},"modified":"2025-12-04T11:06:17","modified_gmt":"2025-12-04T10:06:17","slug":"vendita-infissi-in-pvc-pavia","status":"publish","type":"page","link":"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/","title":{"rendered":"Vendita Infissi in PVC Pavia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"29821\" class=\"elementor elementor-29821\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-989b20a elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"989b20a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9c5b9d elementor-widget elementor-widget-spacer\" data-id=\"f9c5b9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7b07856 e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"7b07856\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccbafd3 elementor-align-center elementor-widget elementor-widget-breadcrumbs\" data-id=\"ccbafd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/nuscospa.com\/it\/\">Home<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83952ff elementor-widget elementor-widget-heading\" data-id=\"83952ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Vendita Infissi in PVC Pavia<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd74988 elementor-widget elementor-widget-heading\" data-id=\"fd74988\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Scopri i nostri <strong>serramenti<\/strong> di alta qualit\u00e0 e richiedi il tuo <strong>preventivo<\/strong> <strong>online<\/strong>!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-532a377 elementor-align-justify elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"532a377\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">TRASFORMA LA TUA CASA CON IL DESIGN DEL FUTURO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c29006d e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"c29006d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-03e7e7d e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"03e7e7d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c1db2e elementor-widget elementor-widget-heading\" data-id=\"0c1db2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">tI CONTATTEREMO <br>ENTRO 24 ORE<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba5070a elementor-widget elementor-widget-image\" data-id=\"ba5070a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"496\" height=\"331\" src=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/11\/immagine-potata-dell-uomo-d-affari-che-si-siede-dalla-tavola-caffe-e-che-analizza-gli-indicatori-sul-computer-portatile-mentre-parlando-dallo-smartphone-concentrati-sull-uomo-1.webp\" class=\"attachment-full size-full wp-image-57782\" alt=\"\" srcset=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/11\/immagine-potata-dell-uomo-d-affari-che-si-siede-dalla-tavola-caffe-e-che-analizza-gli-indicatori-sul-computer-portatile-mentre-parlando-dallo-smartphone-concentrati-sull-uomo-1.webp 496w, https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/11\/immagine-potata-dell-uomo-d-affari-che-si-siede-dalla-tavola-caffe-e-che-analizza-gli-indicatori-sul-computer-portatile-mentre-parlando-dallo-smartphone-concentrati-sull-uomo-1-450x300.webp 450w, https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/11\/immagine-potata-dell-uomo-d-affari-che-si-siede-dalla-tavola-caffe-e-che-analizza-gli-indicatori-sul-computer-portatile-mentre-parlando-dallo-smartphone-concentrati-sull-uomo-1-400x267.webp 400w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-99b066b e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"99b066b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e9e68d elementor-widget elementor-widget-heading\" data-id=\"6e9e68d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">RICEVI la tua richiesta di preventivo<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-387687b elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"387687b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"TL FORM - Top\" aria-label=\"TL FORM - Top\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"29821\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"387687b\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Nusco SpA: dal 1968, porte e infissi per passione\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-nome elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-nome\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[nome]\" id=\"form-field-nome\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-cognome elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-cognome\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tCognome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[cognome]\" id=\"form-field-cognome\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Cognome\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-telefono elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-telefono\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTelefono\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[telefono]\" id=\"form-field-telefono\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Telefono\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-porte elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-porte\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tPorte\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[porte]\" id=\"form-field-porte\" class=\"elementor-field-textual elementor-size-sm\">\n\t\t\t\t\t\t\t\t\t<option value=\"\">Seleziona il tipo di porta <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Moderne\">Moderne<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Classiche\">Classiche<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Scorrevoli\">Scorrevoli<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"In Legno\">In Legno<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-provincia elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-provincia\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tProvincia\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[provincia]\" id=\"form-field-provincia\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\">\n\t\t\t\t\t\t\t\t\t<option value=\"\">Seleziona Provincia <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Agrigento\">AG<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Alessandria\">AL<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ancona\">AN<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Aosta\">AO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Arezzo\">AR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ascoli Piceno\">AP<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Asti\">AT<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Avellino\">AV<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Bari\">BA<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Barletta-Andria-Trani\">BT<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Belluno\">BL<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Benevento\">BN<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Bergamo\">BG<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Biella\">BI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Bologna\">BO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Bolzano\">BZ<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Brescia\">BS<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Brindisi\">BR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Cagliari\">CA<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Caltanissetta\">CL<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Campobasso\">CB<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Caserta\">CE<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Catania\">CT<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Catanzaro\">CZ<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Chieti\">CH<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Como\">CO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Cosenza\">CS<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Cremona\">CR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Crotone\">KR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Cuneo\">CN<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Enna\">EN<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Fermo\">FM<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ferrara\">FE<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Firenze\">FI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Foggia\">FG<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Forl\u00ec-Cesena\">FC<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Frosinone\">FR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Genova\">GE<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Gorizia\">GO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Grosseto\">GR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Imperia\">IM<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Isernia\">IS<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"L\u2019aquila\">AQ<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"La spezia\">SP<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Latina\">LT<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Lecce\">LE<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Lecco\">LC<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Livorno\">LI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Lodi\">LO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Lucca\">LU<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Macerata\">MC<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Mantova\">MN<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Massa-Carrara\">MS<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Matera\">MT<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Messina\">ME<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Milano\">MI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Modena\">MO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Monza e Brianza\">MB<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Napoli\">NA<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Novara\">NO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Nuoro\">NU<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Oristano\">OR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Padova\">PD<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Palermo\">PA<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Parma\">PR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Pavia\">PV<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Perugia\">PG<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Pesaro e Urbino\">PU<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Pescara\">PE<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Piacenza\">PC<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Pisa\">PI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Pistoia\">PT<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Pordenone\">PN<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Potenza\">PZ<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Prato\">PO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ragusa\">RG<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ravenna\">RA<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Reggio Calabria\">RC<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Reggio Emilia\">RE<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Rieti\">RI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Rimini\">RN<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Roma\">RM<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Rovigo\">RO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Salerno\">SA<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Sassari\">SS<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Savona\">SV<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Siena\">SI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Siracusa\">SR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Sondrio\">SO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Sud Sardegna\">SU<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Taranto\">TA<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Teramo\">TE<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Terni\">TR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Torino\">TO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Trapani\">TP<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Trento\">TN<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Treviso\">TV<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Trieste\">TS<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Udine\">UD<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Varese\">VA<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Venezia\">VE<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Verbano-Cusio-Ossola\">VB<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Vercelli\">VC<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Verona\">VR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Vibo valentia\">VV<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Vicenza\">VI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Viterbo\">VT<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-privacy elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-privacy\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tPrivacy\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[privacy]\" id=\"form-field-privacy\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\">\n\t\t\t\t<label for=\"form-field-privacy\">Accetto il trattamento dei dati secondo la <a href=\"https:\/\/nuscospa.com\/it\/cookie-policy\/\" target=\"_blank\"><u>Privacy Policy<\/u><\/a><\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-field_fb9bf3e elementor-col-100\">\n\t\t\t\t\t<div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-md\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Invia La Tua Richiesta<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7024a10 e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"7024a10\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2133b83 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"2133b83\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-14b52b5 elementor-widget elementor-widget-heading\" data-id=\"14b52b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vendita Infissi in PVC: La Chiave per Serramenti di Qualit\u00e0 e Comfort Energetico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cdec79 elementor-widget elementor-widget-heading\" data-id=\"4cdec79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">La scelta dei <strong>serramenti<\/strong> per la propria abitazione o per un progetto di costruzione \u00e8 un aspetto cruciale che pu\u00f2 influenzare non solo l\u2019estetica degli spazi, ma anche il loro comfort e l\u2019efficienza energetica. La <strong>vendita<\/strong> <strong>infissi<\/strong> in <strong>pvc<\/strong> Paviarappresenta una soluzione ideale per chi cerca qualit\u00e0 e convenienza.<br><br>Nel contesto attuale, dove l\u2019attenzione al risparmio energetico \u00e8 sempre pi\u00f9 centrale, l\u2019utilizzo di <strong>infissi<\/strong> in <strong>PVC<\/strong> si dimostra non solo una scelta di design, ma anche una decisione strategica per ridurre i costi di gestione degli edifici. Gli <strong>infissi<\/strong> in <strong>PVC<\/strong> offrono un isolamento termico e acustico superiore, contribuendo a creare ambienti confortevoli e silenziosi. <br><br>Un elemento fondamentale da considerare \u00e8 la qualit\u00e0 dei materiali impiegati. La <strong>vendita<\/strong> <strong>infissi<\/strong> in <strong>pvc<\/strong> Paviagarantisce prodotti realizzati con tecnologie avanzate, capaci di resistere nel tempo e di mantenere elevate prestazioni. Questo significa che investire in <strong>serramenti<\/strong> di qualit\u00e0 non \u00e8 solo un costo iniziale, ma un risparmio a lungo termine.<br><br>L\u2019<strong>acquisto<\/strong> di <strong>infissi<\/strong> in <strong>PVC<\/strong> deve essere fatto con attenzione e competenza. Relying on experts in the field is essential to ensure that you are making the right choices for your specific needs. Infatti, la consulenza di professionisti esperti permette di ricevere un supporto personalizzato, aiutando a individuare la soluzione pi\u00f9 adeguata in base alle caratteristiche dell\u2019immobile e alle esigenze del cliente.<br><br>Grazie alla <em><strong>Vendita Infissi in PVC Pavia<\/strong><\/em>, \u00e8 possibile ottenere <strong>preventivi<\/strong> <strong>online<\/strong> personalizzati e dettagliati, senza la necessit\u00e0 di intermediari. Questo approccio diretto non solo consente di ottenere <strong>prezzi<\/strong> competitivi, ma offre anche la trasparenza necessaria per prendere decisioni informate. I <strong>preventivi<\/strong> <strong>online<\/strong> permettono di visualizzare diverse configurazioni e opzioni, facilitando l\u2019<strong>acquisto<\/strong> della <strong>finestra<\/strong> perfetta per il proprio progetto.<br><br>Un altro aspetto da considerare \u00e8 la facilit\u00e0 di <strong>acquisto<\/strong>. Con un configuratore digitale, i clienti possono ottenere <strong>preventivi<\/strong> immediati, semplificando notevolmente il processo di selezione e <strong>acquisto<\/strong> degli <strong>infissi<\/strong>. Questo \u00e8 particolarmente utile per i rivenditori, le imprese edili e i professionisti del settore, che necessitano di soluzioni rapide e efficaci per soddisfare le richieste dei loro clienti.<br><br>Le prestazioni superiori degli <strong>infissi<\/strong> in <strong>PVC<\/strong>, unite a un servizio di assistenza tecnica specializzata, rendono questa scelta non solo vantaggiosa, ma anche sicura. Con oltre 90.000 <strong>infissi<\/strong> prodotti annualmente, l\u2019esperienza accumulata nel settore consente di offrire prodotti di alta qualit\u00e0, supportati da una garanzia di eccellenza.<br><br>In un mercato in continua evoluzione, gli architetti e i designer d'interni possono contare sulla <strong>vendita<\/strong> <strong>infissi<\/strong> in <strong>pvc<\/strong> Paviaper integrare soluzioni innovative e sostenibili nei loro progetti. I <strong>serramenti<\/strong> in <strong>PVC<\/strong> non solo migliorano l'estetica degli spazi, ma contribuiscono anche a una maggiore efficienza energetica, un aspetto sempre pi\u00f9 ricercato dai clienti nella fascia premium e mass market.<br><br>In sintesi, se si desidera fare un passo significativo verso la qualit\u00e0 e il comfort negli spazi abitativi, affidarsi a esperti nella <em><strong>Vendita Infissi in PVC Pavia<\/strong><\/em>\u00e8 fondamentale. Grazie a un\u2019offerta mirata e a un servizio clienti dedicato, \u00e8 possibile realizzare un vero e proprio breakthrough nella scelta dei <strong>serramenti<\/strong>, con il vantaggio di ottenere non solo prodotti eccellenti, ma anche un supporto professionale lungo tutto il percorso di <strong>acquisto<\/strong>.<br><br>Investire in <strong>infissi<\/strong> di qualit\u00e0 \u00e8 una decisione strategica che porter\u00e0 benefici tangibili nel tempo, trasformando ogni ambiente in uno spazio accogliente e sostenibile.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4df849a elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"4df849a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PARLA CON UN NOSTRO ESPERTO DI ZONA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ac6f0d e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"3ac6f0d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e53da5d e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"e53da5d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78b60e0 elementor-widget elementor-widget-image\" data-id=\"78b60e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"618\" height=\"784\" src=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/12\/infissi-imm.webp\" class=\"attachment-full size-full wp-image-64045\" alt=\"\" srcset=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/12\/infissi-imm.webp 618w, https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/12\/infissi-imm-355x450.webp 355w, https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/12\/infissi-imm-400x507.webp 400w\" sizes=\"(max-width: 618px) 100vw, 618px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-722cb18 e-con-full e-grid e-transform parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"722cb18\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;position&quot;:&quot;absolute&quot;,&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.7,&quot;sizes&quot;:[]},&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0d5222 elementor-widget elementor-widget-counter\" data-id=\"a0d5222\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Anni di<br> esperienza<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"50\" data-from-value=\"25\" data-delimiter=\",\">25<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ddb158 elementor-widget elementor-widget-counter\" data-id=\"1ddb158\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Porte prodotte<br>all'anno<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"120\" data-from-value=\"60\" data-delimiter=\",\">60<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">K<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8bc7ae elementor-widget elementor-widget-counter\" data-id=\"e8bc7ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Infissi prodotti<br>all'anno<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"90\" data-from-value=\"45\" data-delimiter=\",\">45<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-34aaa90 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"34aaa90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-612412c e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"612412c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ddc9b42 elementor-widget elementor-widget-heading\" data-id=\"ddc9b42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Progettazione personalizzata e assistenza dedicata\u00a0<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b001c07 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"b001c07\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-993a5d8 elementor-widget elementor-widget-heading\" data-id=\"993a5d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Installatori\nspecializzati<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-00a8850 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"00a8850\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e30e17d elementor-widget elementor-widget-heading\" data-id=\"e30e17d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Consulenza fiscale\ne iter burocratici snelli<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c5442f e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"2c5442f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3ecd2e elementor-widget elementor-widget-heading\" data-id=\"d3ecd2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Sistemi brevettati per la sicurezza domestica<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-907b006 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"907b006\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e579ca elementor-widget elementor-widget-heading\" data-id=\"9e579ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Offerta completa: finestre, porte, grate, blindati, accessori<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42e3251 e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"42e3251\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-681f0ab elementor-widget elementor-widget-heading\" data-id=\"681f0ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ispirazioni e Stili<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d5e536 elementor-widget elementor-widget-heading\" data-id=\"3d5e536\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Adatta ogni ambiente a chi sei: minimal, innovativo, fashion, linee classiche, tutto quello che cerchi puoi trovarlo da noi.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db2f1ce elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-n-carousel\" data-id=\"db2f1ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;8ad94aa&quot;},{&quot;slide_title&quot;:&quot;Slide #2&quot;,&quot;_id&quot;:&quot;b9908d2&quot;},{&quot;slide_title&quot;:&quot;Slide #3&quot;,&quot;_id&quot;:&quot;3f67121&quot;},{&quot;_id&quot;:&quot;a2e3488&quot;,&quot;slide_title&quot;:&quot;Slide #4&quot;}],&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 4\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b45156 e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"6b45156\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-562c060 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"562c060\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-250a157 elementor-widget elementor-widget-image\" data-id=\"250a157\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#form\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"386\" height=\"541\" src=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/12\/PVC.webp\" class=\"attachment-full size-full wp-image-64029\" alt=\"\" srcset=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/12\/PVC.webp 386w, https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/12\/PVC-321x450.webp 321w\" sizes=\"(max-width: 386px) 100vw, 386px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 4\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-795e2b9 e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"795e2b9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d534753 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"d534753\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bdeca29 elementor-widget elementor-widget-image\" data-id=\"bdeca29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#form\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"386\" height=\"541\" src=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/12\/Alluminio.webp\" class=\"attachment-full size-full wp-image-64031\" alt=\"\" srcset=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/12\/Alluminio.webp 386w, https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/12\/Alluminio-321x450.webp 321w\" sizes=\"(max-width: 386px) 100vw, 386px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 4\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7ff1d6 e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"a7ff1d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f1bb358 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"f1bb358\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70e4ed0 elementor-widget elementor-widget-image\" data-id=\"70e4ed0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#form\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"386\" height=\"541\" src=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/12\/Legno-Alluminio.webp\" class=\"attachment-full size-full wp-image-64033\" alt=\"\" srcset=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/12\/Legno-Alluminio.webp 386w, https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/12\/Legno-Alluminio-321x450.webp 321w\" sizes=\"(max-width: 386px) 100vw, 386px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"4\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 4\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62df380 e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"62df380\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3e0f802 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"3e0f802\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c4054b3 elementor-widget elementor-widget-image\" data-id=\"c4054b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#form\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"386\" height=\"541\" src=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/12\/Sintesyw70.webp\" class=\"attachment-full size-full wp-image-64035\" alt=\"\" srcset=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/12\/Sintesyw70.webp 386w, https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/12\/Sintesyw70-321x450.webp 321w\" sizes=\"(max-width: 386px) 100vw, 386px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c27b7d elementor-align-justify elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"0c27b7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ti richiamiamo entro 24h<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40db32e e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"40db32e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a455f1c elementor-widget elementor-widget-heading\" data-id=\"a455f1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dicono di noi<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15461c0 elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-n-carousel\" data-id=\"15461c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;8ad94aa&quot;},{&quot;slide_title&quot;:&quot;Slide #2&quot;,&quot;_id&quot;:&quot;b9908d2&quot;},{&quot;slide_title&quot;:&quot;Slide #3&quot;,&quot;_id&quot;:&quot;3f67121&quot;},{&quot;_id&quot;:&quot;5fa49ab&quot;,&quot;slide_title&quot;:&quot;Slide #4&quot;}],&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 4\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c17c9a e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"1c17c9a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a86ffff e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"a86ffff\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50b5b6f elementor-widget elementor-widget-heading\" data-id=\"50b5b6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Miriana D'Onofrio<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a771b0b elementor-widget elementor-widget-rating\" data-id=\"a771b0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"5\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"5\" role=\"img\" aria-label=\"Valutazione 5 su 5\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8ed9a2 elementor-widget elementor-widget-heading\" data-id=\"c8ed9a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><b>Affidabili e professionali<\/b>\u00a0<br>\nMateriali di qualit\u00e0 e vasta scelta di modelli. Inoltre la consegna \u00e8 avvenuta nei tempi previsti ed in perfette condizioni. <\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c6ec5a elementor-widget elementor-widget-heading\" data-id=\"3c6ec5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"#form\">Continua<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 4\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1031643 e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"1031643\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6ee666d e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"6ee666d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-745bbc6 elementor-widget elementor-widget-heading\" data-id=\"745bbc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Antonella<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b858df4 elementor-widget elementor-widget-rating\" data-id=\"b858df4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"5\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"5\" role=\"img\" aria-label=\"Valutazione 5 su 5\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b69a1af elementor-widget elementor-widget-heading\" data-id=\"b69a1af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><b>Professionalit\u00e0, qualit\u00e0 e cortesia<\/b><br>\nHo acquistato una porta blindata e sono rimasto estremamente soddisfatta. Fin dal primo contatto ho trovato un team competente,<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd6b29e elementor-widget elementor-widget-heading\" data-id=\"fd6b29e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"#form\">Continua<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 4\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1530ba3 e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"1530ba3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2d6c09b e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"2d6c09b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f7f4db5 elementor-widget elementor-widget-heading\" data-id=\"f7f4db5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Anna Russo<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adf394e elementor-widget elementor-widget-rating\" data-id=\"adf394e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"5\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"5\" role=\"img\" aria-label=\"Valutazione 5 su 5\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e543cb7 elementor-widget elementor-widget-heading\" data-id=\"e543cb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><b>Felicissima di aver scelto Nusco<\/b>\nSecondo me i migliori , ho preso infissi e porte da loro. La qualit\u00e0 \u00e8 ottima. Sono stati tempestivi con la consegna, molto cordiali.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d9d7c4 elementor-widget elementor-widget-heading\" data-id=\"6d9d7c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"#form\">Continua<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"4\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 4\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-696a671 e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"696a671\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ff4a0d6 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"ff4a0d6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d78ad6 elementor-widget elementor-widget-heading\" data-id=\"5d78ad6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Vincenzo Carrano<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6dc062 elementor-widget elementor-widget-rating\" data-id=\"b6dc062\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"5\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"5\" role=\"img\" aria-label=\"Valutazione 5 su 5\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7266b73 elementor-widget elementor-widget-heading\" data-id=\"7266b73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><b>Ottimo rapporto qualit\u00e0\/prezzo<\/b>\u00a0<br>\nProfessionalit\u00e0, cortesia ed ampia scelta tra modelli e colori delle porte, nonch\u00e9 tra i vari accessori. Rapporto prezzo qualit\u00e0 molto buono.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c760df elementor-widget elementor-widget-heading\" data-id=\"3c760df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"#form\">Continua<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ded11f e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"3ded11f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-43000b0 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"43000b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a2f679b elementor-widget elementor-widget-heading\" data-id=\"a2f679b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Scopri la Vendita Infissi in PVC Pavia per Serramenti di Alta Qualit\u00e0 e Prezzi Competitivi!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-583b537 elementor-widget elementor-widget-heading\" data-id=\"583b537\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Nusco S.p.A. \u00e8 leader nella <em><strong>Vendita Infissi in PVC Pavia<\/strong><\/em>, con una clientela soddisfatta che ha rivoluzionato il proprio spazio abitativo. Da oltre 50 anni, i nostri <strong>serramenti<\/strong> in <strong>PVC<\/strong> offrono isolamento termico e acustico superiori. I clienti che scelgono la <em><strong>Vendita Infissi in PVC Pavia<\/strong><\/em> si avvalgono di qualit\u00e0 e convenienza, testimoniando il nostro impegno nel fornire prodotti d'eccellenza. Affidati a noi per la tua prossima ristrutturazione e scopri perch\u00e9 siamo la scelta preferita per la <em><strong>Vendita Infissi in PVC Pavia<\/strong><\/em>.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea8f1e2 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"ea8f1e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Raccontaci il tuo progetto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a80239 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"7a80239\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f1fe59 elementor-widget elementor-widget-image\" data-id=\"5f1fe59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"749\" height=\"574\" src=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/11\/Rectangle-98.webp\" class=\"attachment-full size-full wp-image-57798\" alt=\"\" srcset=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/11\/Rectangle-98.webp 749w, https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/11\/Rectangle-98-450x345.webp 450w, https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/11\/Rectangle-98-700x536.webp 700w, https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/11\/Rectangle-98-400x307.webp 400w\" sizes=\"(max-width: 749px) 100vw, 749px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2a01b59 e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"2a01b59\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c4157e7 elementor-widget elementor-widget-image\" data-id=\"c4157e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"515\" height=\"244\" src=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/11\/Group-60.webp\" class=\"attachment-full size-full wp-image-57796\" alt=\"\" srcset=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/11\/Group-60.webp 515w, https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/11\/Group-60-450x213.webp 450w, https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/11\/Group-60-400x190.webp 400w\" sizes=\"(max-width: 515px) 100vw, 515px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-488b1be e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"488b1be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f879b61 elementor-widget elementor-widget-heading\" data-id=\"f879b61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Domande Frequenti<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a5706e elementor-widget elementor-widget-heading\" data-id=\"5a5706e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">1 Quali sono i materiali utilizzati per i prodotti di Nusco?  <br>Utilizziamo solo materiali di alta qualit\u00e0, garantendo durata e prestazioni ottimali per ogni prodotto.<br><br>2 Offrite assistenza tecnica per i vostri prodotti?  <br>S\u00ec, il nostro team di esperti \u00e8 sempre disponibile per fornire supporto e consulenza su ogni nostra soluzione.<br><br>3 Posso ricevere un <strong>preventivo<\/strong> personalizzato?  <br>Certamente! Puoi richiedere un <strong>preventivo<\/strong> personalizzato direttamente attraverso il nostro sito.<br><br>4 Qual \u00e8 la vostra esperienza nel settore?  <br>Nusco S.p.A. \u00e8 attiva dal 1968 e ha una lunga storia di eccellenza nella produzione di <strong>infissi<\/strong>.<br><br>5 I vostri prodotti sono certificati?  <br>S\u00ec, tutti i nostri articoli sono certificati e rispettano gli standard di qualit\u00e0 pi\u00f9 elevati.<br><br>6 Come posso contattarvi?  <br>Puoi contattarci facilmente compilando il modulo presente sul nostro sito.<br><br>7 Offrite soluzioni su misura?  <br>Assolutamente, le nostre soluzioni sono progettate per soddisfare le esigenze specifiche di ogni cliente.<br><br>8 Quali vantaggi offrite rispetto ai concorrenti?  <br>Siamo in grado di garantire un rapporto qualit\u00e0-prezzo ineguagliabile grazie alla nostra produzione diretta.<br><br>9 \u00c8 possibile vedere i vostri prodotti prima dell'<strong>acquisto<\/strong>?  <br>S\u00ec, \u00e8 possibile richiedere un appuntamento per visionare i nostri prodotti e discuterne in dettaglio.<br><br>10 Dove posso trovare maggiori informazioni sulla <em><strong>Vendita Infissi in PVC Pavia<\/strong><\/em>?  <br>Puoi trovare tutte le informazioni necessarie sul nostro sito, dove parliamo approfonditamente della <em><strong>Vendita Infissi in PVC Pavia<\/strong><\/em> e delle nostre offerte.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf66cd7 elementor-align-justify elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"cf66cd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi ora!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ce63733 e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"ce63733\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-166bb3b elementor-widget elementor-widget-heading\" data-id=\"166bb3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1ead87 elementor-widget elementor-widget-heading\" data-id=\"d1ead87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><div class='accordion-container accordion_trafficloop'><button class='accordion'>Soluzioni e servizi correlati<\/button><div class='panel'><ul class=\"column-list\"><li><a title='Produzione Infissi In Alluminio Pavia' href='https:\/\/nuscospa.com\/it\/produzione-infissi-in-alluminio-pavia\/'>Produzione Infissi In Alluminio Pavia<\/a><\/li><li><a title='Produzione Infissi In Legno Pavia' href='https:\/\/nuscospa.com\/it\/produzione-infissi-in-legno-pavia\/'>Produzione Infissi In Legno Pavia<\/a><\/li><li><a title='Produzione Infissi In Pvc Pavia' href='https:\/\/nuscospa.com\/it\/produzione-infissi-in-pvc-pavia\/'>Produzione Infissi In Pvc Pavia<\/a><\/li><li><a title='Rivenditore Infissi In Alluminio Pavia' href='https:\/\/nuscospa.com\/it\/rivenditore-infissi-in-alluminio-pavia\/'>Rivenditore Infissi In Alluminio Pavia<\/a><\/li><li><a title='Rivenditore Infissi In Legno Pavia' href='https:\/\/nuscospa.com\/it\/rivenditore-infissi-in-legno-pavia\/'>Rivenditore Infissi In Legno Pavia<\/a><\/li><li><a title='Rivenditore Infissi In Pvc Pavia' href='https:\/\/nuscospa.com\/it\/rivenditore-infissi-in-pvc-pavia\/'>Rivenditore Infissi In Pvc Pavia<\/a><\/li><li><a title='Vendita Infissi Con Ecobonus Pavia' href='https:\/\/nuscospa.com\/it\/vendita-infissi-con-ecobonus-pavia\/'>Vendita Infissi Con Ecobonus Pavia<\/a><\/li><li><a title='Vendita Infissi In Alluminio Pavia' href='https:\/\/nuscospa.com\/it\/vendita-infissi-in-alluminio-pavia\/'>Vendita Infissi In Alluminio Pavia<\/a><\/li><li><a title='Vendita Infissi In Legno Pavia' href='https:\/\/nuscospa.com\/it\/vendita-infissi-in-legno-pavia\/'>Vendita Infissi In Legno Pavia<\/a><\/li><\/ul><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96fea1e e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"96fea1e\" data-element_type=\"container\" data-e-type=\"container\" id=\"form\">\n\t\t<div class=\"elementor-element elementor-element-1b7eeb7 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"1b7eeb7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2157ad5 elementor-widget elementor-widget-heading\" data-id=\"2157ad5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">tI CONTATTEREMO <br>ENTRO 24 ORE<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-502878d elementor-widget elementor-widget-image\" data-id=\"502878d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"496\" height=\"331\" src=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/11\/immagine-potata-dell-uomo-d-affari-che-si-siede-dalla-tavola-caffe-e-che-analizza-gli-indicatori-sul-computer-portatile-mentre-parlando-dallo-smartphone-concentrati-sull-uomo-1.webp\" class=\"attachment-full size-full wp-image-57782\" alt=\"\" srcset=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/11\/immagine-potata-dell-uomo-d-affari-che-si-siede-dalla-tavola-caffe-e-che-analizza-gli-indicatori-sul-computer-portatile-mentre-parlando-dallo-smartphone-concentrati-sull-uomo-1.webp 496w, https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/11\/immagine-potata-dell-uomo-d-affari-che-si-siede-dalla-tavola-caffe-e-che-analizza-gli-indicatori-sul-computer-portatile-mentre-parlando-dallo-smartphone-concentrati-sull-uomo-1-450x300.webp 450w, https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/11\/immagine-potata-dell-uomo-d-affari-che-si-siede-dalla-tavola-caffe-e-che-analizza-gli-indicatori-sul-computer-portatile-mentre-parlando-dallo-smartphone-concentrati-sull-uomo-1-400x267.webp 400w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d0ea294 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"d0ea294\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-744d43e elementor-widget elementor-widget-heading\" data-id=\"744d43e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">RICEVI la tua richiesta di preventivo<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea62e80 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"ea62e80\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"TL FORM - Bottom\" aria-label=\"TL FORM - Bottom\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"29821\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"ea62e80\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Nusco SpA: dal 1968, porte e infissi per passione\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-nome elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-nome\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[nome]\" id=\"form-field-nome\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-cognome elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-cognome\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tCognome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[cognome]\" id=\"form-field-cognome\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Cognome\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-telefono elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-telefono\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTelefono\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[telefono]\" id=\"form-field-telefono\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Telefono\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-porte elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-porte\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tPorte\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[porte]\" id=\"form-field-porte\" class=\"elementor-field-textual elementor-size-sm\">\n\t\t\t\t\t\t\t\t\t<option value=\"\">Seleziona il tipo di porta <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Moderne\">Moderne<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Classiche\">Classiche<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Scorrevoli\">Scorrevoli<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"In Legno\">In Legno<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-provincia elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-provincia\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tProvincia\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[provincia]\" id=\"form-field-provincia\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\">\n\t\t\t\t\t\t\t\t\t<option value=\"\">Seleziona Provincia <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Agrigento\">AG<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Alessandria\">AL<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ancona\">AN<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Aosta\">AO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Arezzo\">AR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ascoli Piceno\">AP<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Asti\">AT<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Avellino\">AV<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Bari\">BA<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Barletta-Andria-Trani\">BT<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Belluno\">BL<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Benevento\">BN<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Bergamo\">BG<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Biella\">BI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Bologna\">BO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Bolzano\">BZ<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Brescia\">BS<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Brindisi\">BR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Cagliari\">CA<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Caltanissetta\">CL<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Campobasso\">CB<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Caserta\">CE<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Catania\">CT<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Catanzaro\">CZ<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Chieti\">CH<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Como\">CO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Cosenza\">CS<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Cremona\">CR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Crotone\">KR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Cuneo\">CN<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Enna\">EN<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Fermo\">FM<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ferrara\">FE<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Firenze\">FI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Foggia\">FG<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Forl\u00ec-Cesena\">FC<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Frosinone\">FR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Genova\">GE<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Gorizia\">GO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Grosseto\">GR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Imperia\">IM<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Isernia\">IS<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"L\u2019aquila\">AQ<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"La spezia\">SP<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Latina\">LT<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Lecce\">LE<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Lecco\">LC<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Livorno\">LI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Lodi\">LO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Lucca\">LU<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Macerata\">MC<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Mantova\">MN<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Massa-Carrara\">MS<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Matera\">MT<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Messina\">ME<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Milano\">MI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Modena\">MO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Monza e Brianza\">MB<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Napoli\">NA<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Novara\">NO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Nuoro\">NU<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Oristano\">OR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Padova\">PD<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Palermo\">PA<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Parma\">PR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Pavia\">PV<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Perugia\">PG<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Pesaro e Urbino\">PU<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Pescara\">PE<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Piacenza\">PC<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Pisa\">PI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Pistoia\">PT<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Pordenone\">PN<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Potenza\">PZ<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Prato\">PO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ragusa\">RG<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ravenna\">RA<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Reggio Calabria\">RC<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Reggio Emilia\">RE<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Rieti\">RI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Rimini\">RN<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Roma\">RM<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Rovigo\">RO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Salerno\">SA<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Sassari\">SS<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Savona\">SV<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Siena\">SI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Siracusa\">SR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Sondrio\">SO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Sud Sardegna\">SU<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Taranto\">TA<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Teramo\">TE<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Terni\">TR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Torino\">TO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Trapani\">TP<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Trento\">TN<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Treviso\">TV<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Trieste\">TS<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Udine\">UD<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Varese\">VA<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Venezia\">VE<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Verbano-Cusio-Ossola\">VB<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Vercelli\">VC<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Verona\">VR<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Vibo valentia\">VV<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Vicenza\">VI<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Viterbo\">VT<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-privacy elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-privacy\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tPrivacy\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[privacy]\" id=\"form-field-privacy\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\">\n\t\t\t\t<label for=\"form-field-privacy\">Accetto il trattamento dei dati secondo la <a href=\"https:\/\/nuscospa.com\/it\/cookie-policy\/\" target=\"_blank\"><u>Privacy Policy<\/u><\/a><\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-field_fb9bf3e elementor-col-100\">\n\t\t\t\t\t<div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-md\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Invia La Tua Richiesta<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-99244b9 e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"99244b9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-58b1caf e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"58b1caf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-92d0967 elementor-widget elementor-widget-heading\" data-id=\"92d0967\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">AZIENDA<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdfda0c elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"fdfda0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nuscospa.com\/it\/prodotti\/porte\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Porte<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nuscospa.com\/it\/prodotti\/finestre\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Finestre<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nuscospa.com\/it\/persiane-e-grate\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Persiane e Grate<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nuscospa.com\/it\/cataloghi\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cataloghi<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nuscospa.com\/it\/porte-e-infissi-roma\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nusco Roma<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.configuratorenusco.com\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Configuratore<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-69f07d1 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"69f07d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61cf8f6 elementor-widget elementor-widget-heading\" data-id=\"61cf8f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">SALES<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de7d63a elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"de7d63a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nuscospa.com\/it\/rivenditori\/diventa-un-rivenditore-nusco\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Diventa Rivenditore<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nuscospa.com\/it\/diventa-un-agente-nusco\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Diventa Agente<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nuscospa.com\/it\/franchising\/il-progetto-requisiti\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Apri un Franchising<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9228888 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"9228888\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-94ece05 elementor-widget elementor-widget-heading\" data-id=\"94ece05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">CONTATTI<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ef9ab3 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9ef9ab3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Centralino<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+390815122234\u2028\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>+39 0815122234<\/b><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ba6b7e2 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"ba6b7e2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d62c99c elementor-widget elementor-widget-heading\" data-id=\"d62c99c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">COMMERCIALE<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d23f46 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5d23f46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+3908118915224\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+39 08118915224<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:info@nuscoporte.com\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><u>info@nuscoporte.com<\/u><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1346d3e e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"1346d3e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5bcaa1c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5bcaa1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abfe6a7 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"abfe6a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon- elementor-repeater-item-75fc007\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\"><\/span>\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"14\" height=\"24\" viewBox=\"0 0 14 24\" fill=\"none\"><path d=\"M3.09375 14.0297V24H8.53125V14.0297H12.5859L13.4297 9.44531H8.53125V7.82344C8.53125 5.4 9.48281 4.47188 11.9391 4.47188C12.7031 4.47188 13.3172 4.49062 13.6734 4.52812V0.370313C13.0031 0.1875 11.3625 0 10.4156 0C5.40469 0 3.09375 2.36719 3.09375 7.47187V9.44531H0V14.0297H3.09375Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon- elementor-repeater-item-94204c9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\"><\/span>\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"21\" height=\"21\" viewBox=\"0 0 21 21\" fill=\"none\"><path d=\"M4.70062 20.9995H0.346875V6.97922H4.70062V20.9995ZM2.52141 5.06672C1.12922 5.06672 0 3.91359 0 2.52141C9.96468e-09 1.85269 0.265647 1.21136 0.738503 0.738503C1.21136 0.265647 1.85269 0 2.52141 0C3.19012 0 3.83145 0.265647 4.30431 0.738503C4.77716 1.21136 5.04281 1.85269 5.04281 2.52141C5.04281 3.91359 3.91313 5.06672 2.52141 5.06672ZM20.9953 20.9995H16.6509V14.1745C16.6509 12.548 16.6181 10.462 14.3873 10.462C12.1237 10.462 11.7769 12.2292 11.7769 14.0573V20.9995H7.42781V6.97922H11.6034V8.89172H11.6644C12.2456 7.79016 13.6655 6.62766 15.7838 6.62766C20.19 6.62766 21 9.52922 21 13.298V20.9995H20.9953Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon- elementor-repeater-item-4ddb035\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\"><\/span>\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"23\" height=\"23\" viewBox=\"0 0 23 23\" fill=\"none\"><path d=\"M11.3839 5.54404C8.1542 5.54404 5.54912 8.14912 5.54912 11.3788C5.54912 14.6085 8.1542 17.2136 11.3839 17.2136C14.6136 17.2136 17.2187 14.6085 17.2187 11.3788C17.2187 8.14912 14.6136 5.54404 11.3839 5.54404ZM11.3839 15.1722C9.29678 15.1722 7.59053 13.471 7.59053 11.3788C7.59053 9.28662 9.2917 7.58545 11.3839 7.58545C13.4761 7.58545 15.1772 9.28662 15.1772 11.3788C15.1772 13.471 13.471 15.1722 11.3839 15.1722ZM18.8183 5.30537C18.8183 6.06201 18.2089 6.66631 17.4573 6.66631C16.7007 6.66631 16.0964 6.05693 16.0964 5.30537C16.0964 4.55381 16.7058 3.94443 17.4573 3.94443C18.2089 3.94443 18.8183 4.55381 18.8183 5.30537ZM22.6827 6.68662C22.5964 4.86357 22.18 3.24873 20.8444 1.91826C19.514 0.587793 17.8991 0.171387 16.0761 0.0799805C14.1972 -0.0266602 8.56553 -0.0266602 6.68662 0.0799805C4.86865 0.166309 3.25381 0.582715 1.91826 1.91318C0.582715 3.24365 0.171387 4.8585 0.0799805 6.68154C-0.0266602 8.56045 -0.0266602 14.1921 0.0799805 16.071C0.166309 17.894 0.582715 19.5089 1.91826 20.8394C3.25381 22.1698 4.86357 22.5862 6.68662 22.6776C8.56553 22.7843 14.1972 22.7843 16.0761 22.6776C17.8991 22.5913 19.514 22.1749 20.8444 20.8394C22.1749 19.5089 22.5913 17.894 22.6827 16.071C22.7894 14.1921 22.7894 8.56553 22.6827 6.68662ZM20.2554 18.087C19.8593 19.0823 19.0925 19.8491 18.0921 20.2503C16.594 20.8444 13.0394 20.7073 11.3839 20.7073C9.72842 20.7073 6.16865 20.8394 4.67568 20.2503C3.68037 19.8542 2.91357 19.0874 2.5124 18.087C1.91826 16.589 2.05537 13.0343 2.05537 11.3788C2.05537 9.72334 1.92334 6.16357 2.5124 4.67061C2.9085 3.67529 3.67529 2.9085 4.67568 2.50732C6.17373 1.91318 9.72842 2.05029 11.3839 2.05029C13.0394 2.05029 16.5991 1.91826 18.0921 2.50732C19.0874 2.90342 19.8542 3.67021 20.2554 4.67061C20.8495 6.16865 20.7124 9.72334 20.7124 11.3788C20.7124 13.0343 20.8495 16.594 20.2554 18.087Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6716b68 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6716b68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cc9eac8 e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"cc9eac8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-340750a e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"340750a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd25fb1 elementor-widget elementor-widget-heading\" data-id=\"dd25fb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/nuscospa.com\/it\/privacy-policy\/\"><u>Privacy Policy<\/u><\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-06e205f e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"06e205f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b79d0e elementor-widget elementor-widget-heading\" data-id=\"1b79d0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/nuscospa.com\/it\/cookie-policy\/\"><u>Cookie Policy<\/u><\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ad79b42 e-flex e-con-boxed parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"ad79b42\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-428e105 elementor-widget elementor-widget-heading\" data-id=\"428e105\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Nusco S.p.A. | C.F. e P.IVA 06861021217 80035 Nola-Napoli (Italy) S.S. 7bis km 50.500\nN. Meccanografico NA039308 |\u00a0<a href=\"https:\/\/nuscospa.com\/it\/mappa-del-sito\/\"><u>Mappa del sito<\/u><\/a>\u00a0|\u00a0<a href=\"https:\/\/www.braincomputing.com\/\"><u>Web agency<\/u><\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>TRASFORMA LA TUA CASA CON IL DESIGN DEL FUTURO tI CONTATTEREMO ENTRO 24 ORE RICEVI la tua richiesta di preventivo PARLA CON UN NOSTRO ESPERTO DI ZONA Anni di esperienza 25 + Porte prodotteall&#8217;anno 60 K Infissi prodottiall&#8217;anno 45 + Progettazione personalizzata e assistenza dedicata\u00a0&#8230;<\/p>\n","protected":false},"author":0,"featured_media":28046,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-29821","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vendita Infissi in PVC a Pavia | Nusco S.p.A.<\/title>\n<meta name=\"description\" content=\"Vendita Infissi in PVC a Pavia con Nusco S.p.A.. Serramenti finestre PVC isolanti. Prezzi e preventivi online. Showroom specializzato.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vendita Infissi in PVC a Pavia | Nusco S.p.A.\" \/>\n<meta property=\"og:description\" content=\"Vendita Infissi in PVC a Pavia con Nusco S.p.A.. Serramenti finestre PVC isolanti. Prezzi e preventivi online. Showroom specializzato.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/\" \/>\n<meta property=\"og:site_name\" content=\"Nusco SpA: dal 1968, porte e infissi per passione\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nusco.spa\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-04T10:06:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/07\/nusco-tl-foto-evidenza.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Vendita Infissi in PVC a Pavia | Nusco S.p.A.\" \/>\n<meta name=\"twitter:description\" content=\"Vendita Infissi in PVC a Pavia con Nusco S.p.A.. Serramenti finestre PVC isolanti. Prezzi e preventivi online. Showroom specializzato.\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/\",\"url\":\"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/\",\"name\":\"Vendita Infissi in PVC a Pavia | Nusco S.p.A.\",\"isPartOf\":{\"@id\":\"https:\/\/nuscospa.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/07\/nusco-tl-foto-evidenza.webp\",\"datePublished\":\"2025-07-17T19:22:34+00:00\",\"dateModified\":\"2025-12-04T10:06:17+00:00\",\"description\":\"Vendita Infissi in PVC a Pavia con Nusco S.p.A.. Serramenti finestre PVC isolanti. Prezzi e preventivi online. Showroom specializzato.\",\"breadcrumb\":{\"@id\":\"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/#primaryimage\",\"url\":\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/07\/nusco-tl-foto-evidenza.webp\",\"contentUrl\":\"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/07\/nusco-tl-foto-evidenza.webp\",\"width\":\"500\",\"height\":\"500\",\"caption\":\"[wp-trafficloop-mt tag=\\\"main_title\\\"]\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nuscospa.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vendita Infissi in PVC Pavia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nuscospa.com\/it\/#website\",\"url\":\"https:\/\/nuscospa.com\/it\/\",\"name\":\"Nusco SpA: dal 1968, porte e infissi per passione\",\"description\":\"Nusco SpA \u00e8 leader nella produzione di porte, infissi in legno, legno alluminio e PVC, grate e persiane di sicurezza. Scopri le nostre collezioni!\",\"publisher\":{\"@id\":\"https:\/\/nuscospa.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nuscospa.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nuscospa.com\/it\/#organization\",\"name\":\"Nusco SpA\",\"url\":\"https:\/\/nuscospa.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/nuscospa.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nuscospa.com\/wp-content\/uploads\/2018\/03\/nusco-logo.png\",\"contentUrl\":\"https:\/\/nuscospa.com\/wp-content\/uploads\/2018\/03\/nusco-logo.png\",\"width\":1768,\"height\":744,\"caption\":\"Nusco SpA\"},\"image\":{\"@id\":\"https:\/\/nuscospa.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Nusco.spa\",\"http:\/\/www.linkedin.com\/company\/5103818?trk=tyah&amp;amp;trkInfo=tas:gruppo nusco spa,idx:1-1-1\",\"https:\/\/youtube.com\/@nuscospa3358?si=Y_sAVi-OY5P-hwSM\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vendita Infissi in PVC a Pavia | Nusco S.p.A.","description":"Vendita Infissi in PVC a Pavia con Nusco S.p.A.. Serramenti finestre PVC isolanti. Prezzi e preventivi online. Showroom specializzato.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/","og_locale":"it_IT","og_type":"article","og_title":"Vendita Infissi in PVC a Pavia | Nusco S.p.A.","og_description":"Vendita Infissi in PVC a Pavia con Nusco S.p.A.. Serramenti finestre PVC isolanti. Prezzi e preventivi online. Showroom specializzato.","og_url":"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/","og_site_name":"Nusco SpA: dal 1968, porte e infissi per passione","article_publisher":"https:\/\/www.facebook.com\/Nusco.spa","article_modified_time":"2025-12-04T10:06:17+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/07\/nusco-tl-foto-evidenza.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_title":"Vendita Infissi in PVC a Pavia | Nusco S.p.A.","twitter_description":"Vendita Infissi in PVC a Pavia con Nusco S.p.A.. Serramenti finestre PVC isolanti. Prezzi e preventivi online. Showroom specializzato.","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/","url":"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/","name":"Vendita Infissi in PVC a Pavia | Nusco S.p.A.","isPartOf":{"@id":"https:\/\/nuscospa.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/#primaryimage"},"image":{"@id":"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/#primaryimage"},"thumbnailUrl":"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/07\/nusco-tl-foto-evidenza.webp","datePublished":"2025-07-17T19:22:34+00:00","dateModified":"2025-12-04T10:06:17+00:00","description":"Vendita Infissi in PVC a Pavia con Nusco S.p.A.. Serramenti finestre PVC isolanti. Prezzi e preventivi online. Showroom specializzato.","breadcrumb":{"@id":"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/#primaryimage","url":"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/07\/nusco-tl-foto-evidenza.webp","contentUrl":"https:\/\/nuscospa.com\/wp-content\/uploads\/2025\/07\/nusco-tl-foto-evidenza.webp","width":"500","height":"500","caption":"[wp-trafficloop-mt tag=\"main_title\"]"},{"@type":"BreadcrumbList","@id":"https:\/\/nuscospa.com\/it\/vendita-infissi-in-pvc-pavia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nuscospa.com\/it\/"},{"@type":"ListItem","position":2,"name":"Vendita Infissi in PVC Pavia"}]},{"@type":"WebSite","@id":"https:\/\/nuscospa.com\/it\/#website","url":"https:\/\/nuscospa.com\/it\/","name":"Nusco SpA: dal 1968, porte e infissi per passione","description":"Nusco SpA \u00e8 leader nella produzione di porte, infissi in legno, legno alluminio e PVC, grate e persiane di sicurezza. Scopri le nostre collezioni!","publisher":{"@id":"https:\/\/nuscospa.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nuscospa.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/nuscospa.com\/it\/#organization","name":"Nusco SpA","url":"https:\/\/nuscospa.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nuscospa.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/nuscospa.com\/wp-content\/uploads\/2018\/03\/nusco-logo.png","contentUrl":"https:\/\/nuscospa.com\/wp-content\/uploads\/2018\/03\/nusco-logo.png","width":1768,"height":744,"caption":"Nusco SpA"},"image":{"@id":"https:\/\/nuscospa.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Nusco.spa","http:\/\/www.linkedin.com\/company\/5103818?trk=tyah&amp;amp;trkInfo=tas:gruppo nusco spa,idx:1-1-1","https:\/\/youtube.com\/@nuscospa3358?si=Y_sAVi-OY5P-hwSM"]}]}},"_links":{"self":[{"href":"https:\/\/nuscospa.com\/it\/wp-json\/wp\/v2\/pages\/29821"}],"collection":[{"href":"https:\/\/nuscospa.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nuscospa.com\/it\/wp-json\/wp\/v2\/types\/page"}],"replies":[{"embeddable":true,"href":"https:\/\/nuscospa.com\/it\/wp-json\/wp\/v2\/comments?post=29821"}],"version-history":[{"count":3,"href":"https:\/\/nuscospa.com\/it\/wp-json\/wp\/v2\/pages\/29821\/revisions"}],"predecessor-version":[{"id":64369,"href":"https:\/\/nuscospa.com\/it\/wp-json\/wp\/v2\/pages\/29821\/revisions\/64369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nuscospa.com\/it\/wp-json\/wp\/v2\/media\/28046"}],"wp:attachment":[{"href":"https:\/\/nuscospa.com\/it\/wp-json\/wp\/v2\/media?parent=29821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}